{"id":64,"date":"2022-06-18T19:50:22","date_gmt":"2022-06-18T17:50:22","guid":{"rendered":"http:\/\/www.lucskyturf.com\/?p=64"},"modified":"2022-06-18T21:55:22","modified_gmt":"2022-06-18T19:55:22","slug":"montante-du-dimanche-19-juin","status":"publish","type":"post","link":"https:\/\/www.lucskyturf.com\/index.php\/2022\/06\/18\/montante-du-dimanche-19-juin\/","title":{"rendered":"Montante du dimanche 19 juin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Voici donc arriv\u00e9 le jour du PRIX DE DIANE, \u00e0 l&rsquo;heure ou je publie elles sont encore 18 a viser le troph\u00e9e. Nous ne sommes pas \u00e0 l&rsquo;abri d&rsquo;avoir un ou deux forfait(s) du \u00e0 l&rsquo;\u00e9tat du terrain qui sera sans doute bon (je parie pour un p\u00e9n\u00e9trom\u00e8tre \u00e0 3,2) au vu des temp\u00e9ratures caniculaires qui s\u00e9vissent sur la France depuis plusieurs jours.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"227\" src=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-1024x227.jpg\" alt=\"\" class=\"wp-image-73\" srcset=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-1024x227.jpg 1024w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-300x67.jpg 300w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-768x171.jpg 768w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-1536x341.jpg 1536w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane-1200x267.jpg 1200w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/Prix-de-diane.jpg 1796w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pour demain c&rsquo;est le choix du c\u0153ur qui oriente ma s\u00e9lection, l&rsquo;homme au 160 groupes I, va-t-il enfin finir par \u00e9pingler ce PRIX DE DIANE \u00e0 son palmar\u00e8s, lui qui a remport\u00e9 4 fois l&rsquo;ARC DE TRIOMPHE, 2 fois le PRIX DU JOCKEY CLUB, 2 fois la POULE D&rsquo;ESSAI DES POULAINS, 4 fois  celle DES POULICHES, on ne compte plus ses victoires dans le PRIX D&rsquo;ISPAHAN, ni le GANAY encore moins le ROTHSCHILD (dont 4 fois avec sa c\u00e9l\u00e8bre comparse GOLDIKOVA). Il a gagn\u00e9 sur tous les continents, aussi bien au Japon, qu&rsquo;aux Etats-Unis. Mais le PRIX DE DIANE se refuse \u00e0 lui. Et si demain Olivier Peslier mettait fin \u00e0 cette incongruit\u00e9. Dans le Paris-Turf du jour Yutaka Take c\u00e9l\u00e8bre jockey japonais disait de ne pas s&rsquo;inqui\u00e9ter en citant son exemple, il lui manquait un groupe I pour 2 ans au Japon, et il a fini par le remporter l&rsquo;ann\u00e9e derni\u00e8re \u00e0 l&rsquo;\u00e2ge de 52 ans. Olivier n&rsquo;a encore que 49 ans il a donc encore du temps devant lui.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"399\" src=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/MD_00206120-025-scoopdyga_AGAVE.jpg\" alt=\"\" class=\"wp-image-65\" srcset=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/MD_00206120-025-scoopdyga_AGAVE.jpg 600w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/06\/MD_00206120-025-scoopdyga_AGAVE-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>AGAVE entrainement Andr\u00e9 Fabre, pour la succession du Prince Khalid Abdullah<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Et si demain c&rsquo;\u00e9tait enfin le bon jour. \ud83d\ude0d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc demain 12\u20ac plac\u00e9s sur AGAVE2\ufe0f\u20e3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nouveau solde : 110,60\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici donc arriv\u00e9 le jour du PRIX DE DIANE, \u00e0 l&rsquo;heure ou je publie elles sont encore 18 a viser le troph\u00e9e. Nous ne sommes pas \u00e0 l&rsquo;abri d&rsquo;avoir un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-montante-lucsky"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":4,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/64\/revisions\/74"}],"wp:attachment":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}