{"id":315,"date":"2022-07-10T10:41:19","date_gmt":"2022-07-10T08:41:19","guid":{"rendered":"http:\/\/www.lucskyturf.com\/?p=315"},"modified":"2022-07-10T10:41:24","modified_gmt":"2022-07-10T08:41:24","slug":"reports-de-deauville-du-10-juillet","status":"publish","type":"post","link":"https:\/\/www.lucskyturf.com\/index.php\/2022\/07\/10\/reports-de-deauville-du-10-juillet\/","title":{"rendered":"(Re)ports de Deauville du 10 Juillet"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"333\" src=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/image.png\" alt=\"\" class=\"wp-image-316\" srcset=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/image.png 699w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/image-300x143.png 300w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un peu \u00e0 la fa\u00e7con du patron, je vais vous proposer trois reports aujourd&rsquo;hui pour la r\u00e9union de Deauville. Et comme le patron, j&rsquo;ai valid\u00e9 ces jeux ce matin au PMU&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Report \u00ab\u00a0favori\u00a0\u00bb:<\/strong> 101GP-504GP-801GP. Cotes actuelles: 2.9\/1+1.9\/1+4.3\/1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je pense que 101-Wooton City, 504-Modern Games et 801-Sicilian Defense seront tous trois pay\u00e9s. Apr\u00e8s, si aucun des trois ne gagne sa course, on ne sera pas rembours\u00e9. On devrait l&rsquo;\u00eatre avec au moins un gagnant, ce qui pour moi devrait \u00eatre le cas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Report plus sp\u00e9culatif:<\/strong> 202GP-703GP. Cotes actuelles: 5.7\/1+5.8\/1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vois une tr\u00e8s bonne chance y compris pour la victoire \u00e0 202-Breizh Sky et 703-Le Cadeau. Aucun des deux n&rsquo;est favori, on pourrait \u00eatre rembours\u00e9 ici s&rsquo;ils sont pay\u00e9s tous les deux. Si je ne me suis pas tromp\u00e9 sur Breizh Sky, on devrait \u00eatre pay\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Report de la mort (ou suicidaire ou d\u00e9bile, c&rsquo;est selon):<\/strong> 404GP + 1008-1009 SGP. Cotes actuelles: 12\/1+9.3\/1-18\/1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je vais \u00eatre franc, je ne pensais pas valider autre chose que les deux reports pr\u00e9c\u00e9dents. Mais au vu des cotes, je me suis laiss\u00e9 tenter. Le report d\u00e9marre donc et s&rsquo;arr\u00eatera surement avec 404-Datthirey. Je l&rsquo;ai mis en t\u00eate de ma s\u00e9lection, et \u00e0 plus de 10\/1 dans cette course, m\u00eame le rapport plac\u00e9 sera int\u00e9ressant. Si par miracle donc il est pay\u00e9, le report se terminera dans la derni\u00e8re avec 1008-Feel the Beat et 1009-Morea qui sont mes deux outsiders dans cette course (pour ceux qui ont lu mes s\u00e9lections deauvillaises). On pourrait \u00eatre rembours\u00e9 si un des deux finit dans les trois. Alors encore une fois, la probabilit\u00e9 que celui-ci passe n&rsquo;est pas tr\u00e8s haute, mais si ca veut sourire, ca peut \u00eatre rigolo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voila, y a plus qu&rsquo;\u00e0 maintenant&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un peu \u00e0 la fa\u00e7con du patron, je vais vous proposer trois reports aujourd&rsquo;hui pour la r\u00e9union de Deauville. Et comme le patron, j&rsquo;ai valid\u00e9 ces jeux ce matin au&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[],"class_list":["post-315","post","type-post","status-publish","format-standard","hentry","category-report"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":1,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"predecessor-version":[{"id":317,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/315\/revisions\/317"}],"wp:attachment":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}