{"id":243,"date":"2022-07-03T13:42:33","date_gmt":"2022-07-03T11:42:33","guid":{"rendered":"http:\/\/www.lucskyturf.com\/?p=243"},"modified":"2022-07-03T13:42:35","modified_gmt":"2022-07-03T11:42:35","slug":"montante-du-3-juillet","status":"publish","type":"post","link":"https:\/\/www.lucskyturf.com\/index.php\/2022\/07\/03\/montante-du-3-juillet\/","title":{"rendered":"Montante du 3 juillet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s la d\u00e9ception caus\u00e9e par FORBACH qui n&rsquo;a pu faire mieux que 8\u00e8me retour aujourd&rsquo;hui sur l&rsquo;hippodrome du Val d&rsquo;Or pour le HANDICAP DES HAUTS DE SEINE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une \u00e9preuve une fois de plus bien difficile a d\u00e9chiffrer. Je tente un coup de poker avec MIRASCH1\ufe0f\u20e36\ufe0f\u20e3 actuellement propos\u00e9 \u00e0 22\/1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce pensionnaire d&rsquo;Adrien Fouassier sera associ\u00e9 \u00e0 Maryline Eon et n&rsquo;aura que 51kg a porter. Bien plac\u00e9 dans les stalles de d\u00e9part il peut profiter de ses 2 courses de rentr\u00e9e pour refaire parler de lui en valeur 30,5.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/MD_00189614-006-scoopdyga_MIRASCH.jpg\" alt=\"\" class=\"wp-image-244\" srcset=\"https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/MD_00189614-006-scoopdyga_MIRASCH.jpg 600w, https:\/\/www.lucskyturf.com\/wp-content\/uploads\/2022\/07\/MD_00189614-006-scoopdyga_MIRASCH-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>\ud83d\udcf8ScoopDyga<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Donc 30\u20ac plac\u00e9s sur MIRASCH, nouveau solde : 270\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s la d\u00e9ception caus\u00e9e par FORBACH qui n&rsquo;a pu faire mieux que 8\u00e8me retour aujourd&rsquo;hui sur l&rsquo;hippodrome du Val d&rsquo;Or pour le HANDICAP DES HAUTS DE SEINE. Une \u00e9preuve une&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-243","post","type-post","status-publish","format-standard","hentry","category-montante-lucsky"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":1,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/243\/revisions"}],"predecessor-version":[{"id":245,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/243\/revisions\/245"}],"wp:attachment":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/media?parent=243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/categories?post=243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/tags?post=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}