{"id":1927,"date":"2023-04-02T21:37:08","date_gmt":"2023-04-02T19:37:08","guid":{"rendered":"http:\/\/www.lucskyturf.com\/?p=1927"},"modified":"2023-04-02T22:05:31","modified_gmt":"2023-04-02T20:05:31","slug":"tqq-du-03-04-2023","status":"publish","type":"post","link":"https:\/\/www.lucskyturf.com\/index.php\/2023\/04\/02\/tqq-du-03-04-2023\/","title":{"rendered":"TQQ+ du 03\/04\/2023."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">CHANTILLY. 1600m. Gazon.\/ 4 ans et +\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma s\u00e9lection : 6-8-9-7-4-2-13-5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6\ufe0f\u20e3EXCITING<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je le conseillais derni\u00e8rement lors du Quint\u00e9 disput\u00e9 sur les 1600m de la PSF, o\u00f9 il a termin\u00e9 3\u00e8me \u00e9chouant de tr\u00e8s peu apr\u00e8s avoir tard\u00e9 a trouver l\u2019ouverture. Il a prouv\u00e9 qu\u2019il pouvait gagner  \u00e0 ce niveau aussi bien sur 1600m que sur un peu plus long \u00e0 cette valeur (39). Cette fois ci ce sera sur le gazon, et il  d\u00e9tient \u00e9videmment une toute bonne chance th\u00e9orique, mais j\u2019ai toutefois un doute sur son aptitude aux terrains tr\u00e8s souples. Oblig\u00e9 de le retenir mais pas un penalty\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8\ufe0f\u20e3NORWEGIAN SIR<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est \u00e0 cr\u00e9dit\u00e9 d\u2019un bon effort final derni\u00e8rement \u00e0 Saint-Cloud dans le Quint\u00e9 disput\u00e9 sur 1400m. Un peu pris de vitesse ce jour l\u00e0, il sera mieux sur 1600m ici et le terrain tr\u00e8s souple sera \u00e0 sa guise. Je le trouve tr\u00e8s comp\u00e9titif \u00e0 cette valeur (37,5), m\u00eame s\u2019il faut que tout se passe bien. Avec un bon parcours il a sa chance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9\ufe0f\u20e3GALORD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce 4 ans fait toutes ses courses depuis le d\u00e9but de sa carri\u00e8re. Il semble poss\u00e9der un peu de qualit\u00e9 et \u00e0 l\u2019air de s\u2019adapter \u00e0 tout types de surfaces. Il vient de faire une rentr\u00e9e victorieuse \u00e0 Compi\u00e8gne en terrain lourd et a \u00e9t\u00e9 p\u00e9nalis\u00e9 de 2,5kgs, logiquement. Je le pense encore tr\u00e8s comp\u00e9titif \u00e0 ce niveau car il semble avoir une certaine marge. S\u2019il ne subit pas le contrecoup de cette rentr\u00e9e il devrait de nouveau \u00eatre dangereux, et surtout si le terrain s\u2019alourdit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7\ufe0f\u20e3LUPO NERO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je l\u2019aurai mis en t\u00eate de ma s\u00e9lection si le terrain \u00e9tait tr\u00e8s lourd et si la distance \u00e9tait 1400m, car je pense que \u00e7 est le \u00abcombo\u00a0\u00bb id\u00e9al pour lui. Cependant c\u2019est un cheval qui galope aux avant-postes et qui d\u00e9marre bien, un gros atout \u00e0 Chantilly o\u00f9 il devient compliqu\u00e9 de revenir de l\u2019arri\u00e8re-garde parfois. Il a tir\u00e9 un bon num\u00e9ro de corde (3) et devrait vite prendre la t\u00eate en d\u00e9but de course. Il ne d\u00e9m\u00e9rite pas l\u00e0 derni\u00e8re fois \u00e0 Saint-Cloud pour ses d\u00e9buts \u00e0 ce niveau. S\u2019il pleut et que le terrain s\u2019alourdit m\u00e9fiez vous en \u2026!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4\ufe0f\u20e3SIMONS KING<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il partira s\u00fbrement d\u00e9laiss\u00e9 au betting mais je lui vois tout de m\u00eame une chance m\u00eame s\u2019il fait une rentr\u00e9e. En effet, l\u2019an dernier \u00e0 cette \u00e9poque il \u00e9tait comp\u00e9titif en 38,5 de valeur \u00e0 ce niveau et avait m\u00eame gagn\u00e9 sur le parcours du jour, en terrain tr\u00e8s souple. Il avait \u00e9galement remport\u00e9 son Quint\u00e9 en 40 de valeur \u00e0 Longchamp. Ensuite \u00e7\u2019\u00e9tait devenu compliqu\u00e9 suite \u00e0 sa p\u00e9nalisation. Redescendu en 39,5 ici, il va s\u00fbrement refaire surface t\u00f4t ou tard. Il se monte de l\u2019avant et ce trac\u00e9 lui convient tr\u00e8s bien. Autant avoir un coup d\u2019avance, je pense qu\u2019il faut le suivre, et il faut parfois prendre des risques alors je le garde d\u00e8s sa rentr\u00e9e. Coup de poker.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2\ufe0f\u20e3DANTES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il n\u2019est pas g\u00e2t\u00e9 par le tirage au sort des num\u00e9ros de corde ces temps-ci. Retrouver le gazon ne sera s\u00fbrement pas un inconv\u00e9nient pour lui mais avec ce num\u00e9ro de corde (16) la t\u00e2che se complique, tout du moins pour la victoire. Il faudra \u00e9videmment compter sur le talent de Maxime Guyon, mais, m\u00eame s\u2019il parait toujours comp\u00e9titif dans cette cat\u00e9gorie( il l\u2019a prouv\u00e9 \u00e0 Cagnes cet hiver), je le range plut\u00f4t parmi les outsiders. Pour une place.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1\ufe0f\u20e33\ufe0f\u20e3COME SAY HI<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">il se retrouve vraiment bien plac\u00e9 sur l\u2019\u00e9chelle des valeurs ! En Septembre 2022, il terminait 4eme sur ce parcours dans un Quint\u00e9 (en \u00e9tant malheureux) remport\u00e9 par GOLDINO BELLO (qui est toujours comp\u00e9titif ) \u00e0 poids \u00e9gal\u2026! cette fois il re\u00e7oit 7 kgs de ce dernier ce qui est \u00e9norme dans un handicap (et son mentor accorde une livre \u00e0 Sebastien Maillot pour le monter \u00e0 53 kgs!) Certes, il n\u2019est pas tr\u00e8s r\u00e9gulier mais il ne faut pas l\u2019oublier \u00e0 mon avis. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5\ufe0f\u20e3GOLDINO BELLO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son mentor l\u2019annonce en forme et pr\u00eat \u00e0 bien courir d\u2019entr\u00e9e de jeu. On a vu r\u00e9cemment ses compagnons d\u2019\u00e9curie , LONDON ROYAL et MEMORY DREAM bien se comporter dans les Quint\u00e9s. Il avait gagn\u00e9 de belle mani\u00e8re sur ce parcours l\u2019an dernier en 36 de valeur, mais n\u2019a pas r\u00e9p\u00e9t\u00e9 ensuite \u00e0 Longchamp. A lui de montrer qu\u2019il est toujours comp\u00e9titif en 39,5. Je le garde pour une place car \u00e7 est tout de m\u00eame une rentr\u00e9e. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHANTILLY. 1600m. Gazon.\/ 4 ans et +\/ Ma s\u00e9lection : 6-8-9-7-4-2-13-5 6\ufe0f\u20e3EXCITING Je le conseillais derni\u00e8rement lors du Quint\u00e9 disput\u00e9 sur les 1600m de la PSF, o\u00f9 il a termin\u00e9&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-1927","post","type-post","status-publish","format-standard","hentry","category-etude-quinte"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/1927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/comments?post=1927"}],"version-history":[{"count":1,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/1927\/revisions"}],"predecessor-version":[{"id":1928,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/posts\/1927\/revisions\/1928"}],"wp:attachment":[{"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/media?parent=1927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/categories?post=1927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lucskyturf.com\/index.php\/wp-json\/wp\/v2\/tags?post=1927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}